{"id":3938,"date":"2020-01-07T16:20:59","date_gmt":"2020-01-07T16:20:59","guid":{"rendered":"https:\/\/www.echlorial.fr\/blog\/?p=3938"},"modified":"2022-07-06T11:04:12","modified_gmt":"2022-07-06T11:04:12","slug":"cure-detox","status":"publish","type":"post","link":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/","title":{"rendered":"Cure d\u00e9tox"},"content":{"rendered":"<p><span style=\"font-size: 12pt;\">Bonjour, j<\/span><span style=\"font-size: 12pt;\">e termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables.<\/span><br \/>\n<span style=\"font-size: 12pt;\"> En effet, j&rsquo;avais r\u00e9alis\u00e9 une analyse d&rsquo;urine avant traitement et j&rsquo;avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">Aujourd&rsquo;hui, ma cure est presque termin\u00e9e et je viens de recevoir les r\u00e9sultats de ma derni\u00e8re analyse: 0.4 :microgr\/gr cr\u00e9atinine.<\/span><br \/>\n<span style=\"font-size: 12pt;\"> C&rsquo;est incroyable mais c&rsquo;est bien la r\u00e9alit\u00e9.\u00a0<\/span><span style=\"font-size: 12pt;\">Je vous remercie vivement pour la qualit\u00e9 de vos produits.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"> Je me sens en outre en bien meilleure forme et je n&rsquo;ai pas encore eu le moindre rhume depuis le d\u00e9but du traitement, ce qui n&rsquo;est jamais arriv\u00e9 depuis de nombreuses ann\u00e9es.<\/span><br \/>\n<span style=\"font-size: 12pt;\"> Apr\u00e8s ma cure, je souhaiterais continuer \u00e0 prendre de la chlorella et de la spiruline tout au long de l&rsquo;ann\u00e9e afin de b\u00e9n\u00e9ficier de l&rsquo;effet detox et des nombreux autres avantages. Je fais pas mal de sport et je suis convaincu des b\u00e9n\u00e9fices apport\u00e9s par tous ces nutriments.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"> J&rsquo;aimerais aussi faire une cure d&rsquo;astasanthine mais je voudrais savoir \u00e0 quelle p\u00e9riode il est pr\u00e9f\u00e9rable de la faire, pendant combien de temps et combien de fois par an?<\/span><br \/>\n<span style=\"font-size: 12pt;\"> De nouveau, f\u00e9licitations pour vos produits.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j&rsquo;avais r\u00e9alis\u00e9 une analyse d&rsquo;urine avant traitement et j&rsquo;avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine). Aujourd&rsquo;hui, ma cure est presque termin\u00e9e et je viens de recevoir les r\u00e9sultats [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[45,4],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cure d\u00e9tox (t\u00e9moignage)<\/title>\n<meta name=\"description\" content=\"Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j&#039;avais r\u00e9alis\u00e9 une analyse d&#039;urine avant traitement et j&#039;avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cure d\u00e9tox (t\u00e9moignage)\" \/>\n<meta property=\"og:description\" content=\"Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j&#039;avais r\u00e9alis\u00e9 une analyse d&#039;urine avant traitement et j&#039;avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/\" \/>\n<meta property=\"og:site_name\" content=\"eChlorial\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-07T16:20:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T11:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.echlorial.fr\/blog\/wp-content\/uploads\/2015\/03\/Avatar-Homme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_echlorial\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_echlorial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/\",\"url\":\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/\",\"name\":\"Cure d\u00e9tox (t\u00e9moignage)\",\"isPartOf\":{\"@id\":\"https:\/\/www.echlorial.com\/blog\/#website\"},\"datePublished\":\"2020-01-07T16:20:59+00:00\",\"dateModified\":\"2022-07-06T11:04:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.echlorial.com\/blog\/#\/schema\/person\/0e76c63d04141dd4ae797ce19887e7a6\"},\"description\":\"Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j'avais r\u00e9alis\u00e9 une analyse d'urine avant traitement et j'avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.echlorial.fr\/blog\/cure-detox\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.echlorial.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9moignages\",\"item\":\"https:\/\/www.echlorial.com\/blog\/category\/chlorella-testimonials\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cure d\u00e9tox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.echlorial.com\/blog\/#website\",\"url\":\"https:\/\/www.echlorial.com\/blog\/\",\"name\":\"eChlorial\",\"description\":\"Chlorella extra pure cultiv\u00e9e sous tube de verre en Allemagne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.echlorial.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.echlorial.com\/blog\/#\/schema\/person\/0e76c63d04141dd4ae797ce19887e7a6\",\"name\":\"admin_echlorial\",\"sameAs\":[\"http:\/\/www.echlorial.fr\"],\"url\":\"https:\/\/www.echlorial.fr\/blog\/author\/admin_echlorial\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cure d\u00e9tox (t\u00e9moignage)","description":"Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j'avais r\u00e9alis\u00e9 une analyse d'urine avant traitement et j'avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/","og_locale":"fr_FR","og_type":"article","og_title":"Cure d\u00e9tox (t\u00e9moignage)","og_description":"Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j'avais r\u00e9alis\u00e9 une analyse d'urine avant traitement et j'avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).","og_url":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/","og_site_name":"eChlorial","article_published_time":"2020-01-07T16:20:59+00:00","article_modified_time":"2022-07-06T11:04:12+00:00","og_image":[{"width":1900,"height":254,"url":"https:\/\/www.echlorial.fr\/blog\/wp-content\/uploads\/2015\/03\/Avatar-Homme.jpg","type":"image\/jpeg"}],"author":"admin_echlorial","twitter_misc":{"\u00c9crit par":"admin_echlorial","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/","url":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/","name":"Cure d\u00e9tox (t\u00e9moignage)","isPartOf":{"@id":"https:\/\/www.echlorial.com\/blog\/#website"},"datePublished":"2020-01-07T16:20:59+00:00","dateModified":"2022-07-06T11:04:12+00:00","author":{"@id":"https:\/\/www.echlorial.com\/blog\/#\/schema\/person\/0e76c63d04141dd4ae797ce19887e7a6"},"description":"Bonjour, je termine bient\u00f4t ma cure detox avec votre chlorella. Les r\u00e9sultats sont incroyables. En effet, j'avais r\u00e9alis\u00e9 une analyse d'urine avant traitement et j'avais un exc\u00e8s de plomb assez important : presque 3 fois la dose maximale autoris\u00e9e (14,81 microgr\/gr creatinine).","breadcrumb":{"@id":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.echlorial.fr\/blog\/cure-detox\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.echlorial.fr\/blog\/cure-detox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.echlorial.fr\/"},{"@type":"ListItem","position":2,"name":"T\u00e9moignages","item":"https:\/\/www.echlorial.com\/blog\/category\/chlorella-testimonials\/"},{"@type":"ListItem","position":3,"name":"Cure d\u00e9tox"}]},{"@type":"WebSite","@id":"https:\/\/www.echlorial.com\/blog\/#website","url":"https:\/\/www.echlorial.com\/blog\/","name":"eChlorial","description":"Chlorella extra pure cultiv\u00e9e sous tube de verre en Allemagne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.echlorial.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.echlorial.com\/blog\/#\/schema\/person\/0e76c63d04141dd4ae797ce19887e7a6","name":"admin_echlorial","sameAs":["http:\/\/www.echlorial.fr"],"url":"https:\/\/www.echlorial.fr\/blog\/author\/admin_echlorial\/"}]}},"_links":{"self":[{"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/posts\/3938"}],"collection":[{"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/comments?post=3938"}],"version-history":[{"count":5,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/posts\/3938\/revisions"}],"predecessor-version":[{"id":6232,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/posts\/3938\/revisions\/6232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/media?parent=3938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/categories?post=3938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.echlorial.fr\/blog\/wp-json\/wp\/v2\/tags?post=3938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}